{"id":22108,"date":"2025-06-28T12:32:29","date_gmt":"2025-06-28T10:32:29","guid":{"rendered":"https:\/\/www.stepv.upv.es\/?p=22108"},"modified":"2025-07-07T13:57:04","modified_gmt":"2025-07-07T11:57:04","slug":"el-protocol-de-la-vergonya","status":"publish","type":"post","link":"https:\/\/www.stepv.upv.es\/va\/el-protocol-de-la-vergonya\/","title":{"rendered":"El protocol de la vergonya"},"content":{"rendered":"<p>Recentment s\u2019ha aprovat el nou protocol d\u2019enviament de correus massius a la UPV. Un protocol que, sota l\u2019excusa de \u201creduir el volum de correus\u201d, t\u00e9 com a objectiu principal minvar la veu dels sindicats. Vicent us ho contava <a href=\"https:\/\/youtu.be\/s_I0VKNmVf8?si=D1x_lVcv9N8oKgNd\" title=\"protocol de la vergonya\">aix\u00ed<\/a>.<\/p>\n<p>Aquest protocol estableix que, per rebre informaci\u00f3 sindical, caldr\u00e0 seguir un proc\u00e9s de subscripci\u00f3 espec\u00edfic. \u00c9s a dir, s\u2019implanta una barrera d&#8217;acc\u00e9s a la informaci\u00f3 que hauria de ser un dret: el dret a estar informat pels teus representants. Aix\u00f2 s\u00ed, continuar\u00e0s rebent \u2014sense opci\u00f3 de desubscriure\u2019t\u2014 el tradicional correu nadalenc del rector, ple d\u2019autoelogis sobre \u201clo bien que lo hacemos\u201d.<\/p>\n<p>Tot plegat s\u2019amaga darrere d\u2019un suposat informe de protecci\u00f3 de dades \u2014el comod\u00ed de sempre\u2014 que, casualment, s\u2019ha encarregat expressament per justificar la nova norma, i no a l\u2019inrev\u00e9s. Tot plegat fa molta olor de muntatge ad hoc.<\/p>\n<p>Des del nostre col\u00b7lectiu hem registrat les corresponents al\u00b7legacions, deixant clar que aquesta mesura \u00e9s un pas m\u00e9s cap a la limitaci\u00f3 de les veus cr\u00edtiques. Perqu\u00e8 sabem que sempre us hem informat amb celeritat i rigor, denunciant les decisions que us afecten. I aix\u00f2, evidentment, molesta.<\/p>\n<p>Amb aquest protocol, volen reduir la nostra capacitat de comunicar-vos qu\u00e8 fan, qu\u00e8 amaguen i qu\u00e8 planegen. I aix\u00ed, sense fiscalitzaci\u00f3 ni pressi\u00f3 p\u00fablica, ja podran fer i desfer al seu gust durant els propers sis anys.<\/p>","protected":false},"excerpt":{"rendered":"<p>Recentment s\u2019ha aprovat el nou protocol d\u2019enviament de correus massius a la UPV. Un protocol que, sota l\u2019excusa de \u201creduir el volum de correus\u201d, t\u00e9 com a objectiu principal minvar la veu dels sindicats. Vicent us ho contava aix\u00ed. Aquest protocol estableix que, per rebre informaci\u00f3 sindical, caldr\u00e0 seguir un proc\u00e9s de subscripci\u00f3 espec\u00edfic. \u00c9s [&hellip;]<\/p>\n","protected":false},"author":29775,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1099451],"tags":[],"class_list":["post-22108","post","type-post","status-publish","format-standard","hentry","category-censura"],"_links":{"self":[{"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/posts\/22108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/users\/29775"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/comments?post=22108"}],"version-history":[{"count":0,"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/posts\/22108\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/media?parent=22108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/categories?post=22108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/tags?post=22108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}