{"id":21454,"date":"2024-05-31T11:39:45","date_gmt":"2024-05-31T09:39:45","guid":{"rendered":"https:\/\/www.stepv.upv.es\/?p=21454"},"modified":"2024-05-31T11:52:13","modified_gmt":"2024-05-31T09:52:13","slug":"barem-per-a-la-contractacio-de-nou-professorat-associat","status":"publish","type":"post","link":"https:\/\/www.stepv.upv.es\/va\/barem-per-a-la-contractacio-de-nou-professorat-associat\/","title":{"rendered":"Barem per a la contractaci\u00f3 de nou Professorat Associat"},"content":{"rendered":"<p>Les necessitats docents del curs que ve provocaran una paradoxa: <strong>el professorat associat de nova incorporaci\u00f3 tindr\u00e0 contractes indefinits, mentre seguim sense estabilitzar al professorat que ja treballa a la UPV<\/strong>.<\/p>\n<p>Mentre reclamem una soluci\u00f3 a aquesta situaci\u00f3 transit\u00f2ria, <strong>s&#8217;han aprovat en Mesa General de Negociaci\u00f3 els barems que regiran les noves contractacions <\/strong><a href=\"https:\/\/www.stepv.upv.es\/wp-content\/uploads\/2024\/05\/Barem-acordat.pdf\">que pots llegir aqu\u00ed<\/a>. De nou amb el nostre vot a favor i de nou amb la sensaci\u00f3 que la predisposici\u00f3 del vicerector a arribar a acords ha canviat a millor.<\/p>\n<p><strong>A proposta d\u2019STEPV, l&#8217;experi\u00e8ncia professional i les compet\u00e8ncies docents seran els<\/strong> <strong>m\u00e8rits m\u00e9s valorats<\/strong>, un plantejament molt m\u00e9s alineat amb l&#8217;especificitat d&#8217;aquest perfil tal com est\u00e0 definit en la llei. Aix\u00ed, el nou barem considerar\u00e0 aquests \u00e0mbits en un 75% de la puntuaci\u00f3 total del curr\u00edculum, 50% i 25% en cada apartat, respectivament. Altres aspectes nous de l&#8217;acord s\u00f3n els seg\u00fcents:<\/p>\n<ul>\n<li>S&#8217;ha aclarit i simplificat la classificaci\u00f3 de m\u00e8rits, deixant en l&#8217;apartat docent \u00fanicament aquells referits a la <strong>doc\u00e8ncia universit\u00e0ria<\/strong>.<\/li>\n<li>S&#8217;inclouen <strong>m\u00e8rits de transfer\u00e8ncia<\/strong>, on aquest tipus de perfils tenen majors possibilitats d&#8217;aportaci\u00f3 a l&#8217;\u00e0mbit acad\u00e8mic, refor\u00e7ant aix\u00ed el seu marcat rol d&#8217;enlla\u00e7 entre la pr\u00e0ctica professional real i l&#8217;aula.<\/li>\n<\/ul>\n<p>Aquest barem, despr\u00e9s de la seua aprovaci\u00f3 en el Consell de Govern, haur\u00e0 de ser <strong>aplicable ja en les places a convocar de cara a la cobertura de necessitats del pr\u00f2xim curs acad\u00e8mic 2024\/2025<\/strong>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Les necessitats docents del curs que ve provocaran una paradoxa: el professorat associat de nova incorporaci\u00f3 tindr\u00e0 contractes indefinits, mentre seguim sense estabilitzar al professorat que ja treballa a la UPV. Mentre reclamem una soluci\u00f3 a aquesta situaci\u00f3 transit\u00f2ria, s&#8217;han aprovat en Mesa General de Negociaci\u00f3 els barems que regiran les noves contractacions que pots [&hellip;]<\/p>\n","protected":false},"author":21175,"featured_media":321,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[843674],"tags":[],"class_list":["post-21454","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acords-i-negociacions"],"_links":{"self":[{"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/posts\/21454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/users\/21175"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/comments?post=21454"}],"version-history":[{"count":0,"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/posts\/21454\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/media\/321"}],"wp:attachment":[{"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/media?parent=21454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/categories?post=21454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/tags?post=21454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}