{"id":20740,"date":"2023-09-06T11:58:55","date_gmt":"2023-09-06T09:58:55","guid":{"rendered":"https:\/\/www.stepv.upv.es\/?p=20740"},"modified":"2024-03-04T11:41:54","modified_gmt":"2024-03-04T10:41:54","slug":"sobre-els-programes-de-teletreball","status":"publish","type":"post","link":"https:\/\/www.stepv.upv.es\/va\/sobre-els-programes-de-teletreball\/","title":{"rendered":"Sobre els programes de teletreball"},"content":{"rendered":"<p>Com el fam\u00f3s meme: quan ho demanes per\u00a0<i>Aliexpress\u00a0<\/i>quan ho reps, l\u2019acord de 27 de juliol de la comissi\u00f3 acad\u00e8mica i de recursos humans pel qual s\u2019aproven alguns\u00a0<strong>programes de teletreball<\/strong>, en opini\u00f3 d\u2019STEPV,\u00a0<strong>no ha cobert les expectatives que genera el reglament<\/strong>.<\/p>\n<p>\u2022 L\u2019esperit del reglament parla de mantindre un\u00a0<strong>equilibri adequat entre presencialitat i teletreball i de recon\u00e9ixer l\u2019heterogene\u00eftat<\/strong>\u00a0de les activitats professionals adaptant els programes a les situacions reals.<\/p>\n<div><\/div>\n<p>Per\u00f2 sembla que els programes han trobat aquest equilibri en l\u2019<strong>homogene\u00eftat d\u2019un dia per tothom<\/strong>, sense difer\u00e8ncies entre categories professionals amb funcions totalment diferents. I\u00a0<strong>aix\u00f2 si el programa recull alguna de les funcions de la teua categoria<\/strong>\u00a0professional, que si no quedes\u00a0<strong>excl\u00f2s de forma t\u00e0cita<\/strong>.<\/p>\n<div><\/div>\n<p>\u2022 El reglament tamb\u00e9 recull una\u00a0<strong>comissi\u00f3 amb la funci\u00f3<\/strong>,entre d\u2019altres,<strong>\u00a0de fer el seguiment del desenvolupament<\/strong>\u00a0d\u2019aquests programes.<\/p>\n<div><\/div>\n<p>Per\u00f2 les persones que la integren, per la part sindical almenys,\u00a0<strong>s\u2019han assabentat dels programes amb la publicaci\u00f3<\/strong>, sense cap participaci\u00f3 o informe.<\/p>\n<p>Tamb\u00e9 ens crida l\u2019atenci\u00f3 que la comissi\u00f3 econ\u00f2mica i de recursos humans acorde l\u2019<strong>extinci\u00f3 del teletreball en aquells CDIS on no s\u2019ha aprovat cap programa<\/strong>, ja no sols per \u201ccastigar\u201d a les persones treballadores perqu\u00e8 l<strong>a persona responsable no haja fet el seu treball<\/strong>, sin\u00f3 perqu\u00e8, a m\u00e9s a m\u00e9s,\u00a0<strong>\u00e9s<\/strong>\u00a0clarament\u00a0<strong>incompetent per fer-ho<\/strong>.<\/p>\n<p>I com no parlar de la\u00a0<strong>incapacitat de l\u2019administraci\u00f3 de mesurar el nostre treball amb indicadors diferents de la satisfacci\u00f3<\/strong>\u00a0dels usuaris, la qual cosa impedira que un programa de teletreball prospere tot i que augmente l\u2019efici\u00e8ncia dels processos si els usuaris prefereixen veure\u2019ns a les nostres cadires.<\/p>\n<p>Aix\u00ed, en STEPV considerem que els programes de teletreball tenen\u00a0<strong>prou marge de millora<\/strong>\u00a0i que no s\u00f3n els que esper\u00e0vem, per\u00f2 a la fi,\u00a0<b>s\u00f3n les vostres opinions les que ens importen<\/b>.<\/p>\n<p>I com per a aquesta universitat nom\u00e9s importa la satisfacci\u00f3,\u00a0<a href=\"https:\/\/forms.gle\/n9FQjmY86A87LcWr6\" target=\"_blank\" rel=\"noopener\">aix\u00f2 \u00e9s el que vos demanem que expresseu, mitjan\u00e7ant aquest formulari<\/a>.<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Com el fam\u00f3s meme: quan ho demanes per\u00a0Aliexpress\u00a0quan ho reps, l\u2019acord de 27 de juliol de la comissi\u00f3 acad\u00e8mica i de recursos humans pel qual s\u2019aproven alguns\u00a0programes de teletreball, en opini\u00f3 d\u2019STEPV,\u00a0no ha cobert les expectatives que genera el reglament. \u2022 L\u2019esperit del reglament parla de mantindre un\u00a0equilibri adequat entre presencialitat i teletreball i de [&hellip;]<\/p>\n","protected":false},"author":21175,"featured_media":20297,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[843674],"tags":[],"class_list":["post-20740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acords-i-negociacions"],"_links":{"self":[{"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/posts\/20740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/users\/21175"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/comments?post=20740"}],"version-history":[{"count":0,"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/posts\/20740\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/media\/20297"}],"wp:attachment":[{"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/media?parent=20740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/categories?post=20740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/tags?post=20740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}