{"id":19746,"date":"2022-02-09T09:05:00","date_gmt":"2022-02-09T08:05:00","guid":{"rendered":"https:\/\/www.stepv.upv.es\/?p=19746"},"modified":"2022-02-09T09:05:00","modified_gmt":"2022-02-09T08:05:00","slug":"els-tribunals-doposicio-a-la-upv-i-lebep","status":"publish","type":"post","link":"https:\/\/www.stepv.upv.es\/va\/els-tribunals-doposicio-a-la-upv-i-lebep\/","title":{"rendered":"Els tribunals d\u2019oposici\u00f3 a la UPV i L\u2019EBEP"},"content":{"rendered":"<p>L\u2019article 60.2 de l\u2019EBEP indica que\u00a0<strong>el personal d\u2019elecci\u00f3 o de designaci\u00f3 pol\u00edtica no pot formar part dels \u00f2rgans de selecci<\/strong>\u00f3, tanmateix no hi ha tribunal a la UPV que no presidisca algun\u00a0<strong>vicerector o vicerectora, director o directora d\u2019\u00c0rea o de Centr<\/strong><strong>e<\/strong>.<\/p>\n<p>Poc importa que tamb\u00e9 siguen personal amb vinculaci\u00f3 permanent amb la Universitat, perqu\u00e8 la seua designaci\u00f3 nom\u00e9s est\u00e0 motivada pel seu c\u00e0rrec de govern. Aix\u00ed,\u00a0<strong>reclamem p\u00fablicament al rector que complisca la llei i excloga el seu equip dels tribunals de selecci\u00f3.<\/strong><\/p>\n<h2>Membres electes dels \u00f2rgans unitaris i delegats o delegades sindicals<\/h2>\n<p><strong>L\u2019EBEP no prohibeix<\/strong>\u00a0la participaci\u00f3 en tribunals de selecci\u00f3 d\u2019aquelles persones que s\u00f3n\u00a0<strong>membres de les Juntes de Personal o Comit\u00e9s d\u2019Empresa, tampoc a les persones Delegades sindicals.<\/strong>\u00a0La llei, per\u00f2, s\u00ed que\u00a0<strong>prohibeix que els sindicats designen<\/strong>\u00a0membres en els tribunals, com es feia abans.<\/p>\n<p>Tot i aix\u00f2, STEPV ent\u00e9n la preocupaci\u00f3 d\u2019UGT sobre el nomenament de membres electes dels \u00f2rgans unitaris i delegats o delegades sindicals en els tribunals de selecci\u00f3 de personal, en atenci\u00f3 a\u00a0<strong>les pol\u00e8miques que va haver-hi a la UPV en temps anteriors<\/strong>\u00a0i que UGT recordar\u00e0 amb molta seguretat.<\/p>\n<p>S\u00f3n casos en qu\u00e8\u00a0<strong>nom\u00e9s cal ser coherent i presentar l\u2019abstenci\u00f3<\/strong>\u00a0en con\u00e9ixer el nomenament,\u00a0<strong>com fem en STEPV.<\/strong>\u00a0Si b\u00e9, considerem que\u00a0<strong>seria recomanable que l\u2019administraci\u00f3 notificara al personal<\/strong>\u00a0la designaci\u00f3 com a membre d\u2019un tribunal\u00a0<strong>abans de la publicaci\u00f3,<\/strong>\u00a0per poder presentar l\u2019abstenci\u00f3 si escau.<\/p>","protected":false},"excerpt":{"rendered":"<p>L\u2019article 60.2 de l\u2019EBEP indica que\u00a0el personal d\u2019elecci\u00f3 o de designaci\u00f3 pol\u00edtica no pot formar part dels \u00f2rgans de selecci\u00f3, tanmateix no hi ha tribunal a la UPV que no presidisca algun\u00a0vicerector o vicerectora, director o directora d\u2019\u00c0rea o de Centre. Poc importa que tamb\u00e9 siguen personal amb vinculaci\u00f3 permanent amb la Universitat, perqu\u00e8 la [&hellip;]<\/p>\n","protected":false},"author":14845,"featured_media":13427,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64],"tags":[],"class_list":["post-19746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/posts\/19746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/users\/14845"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/comments?post=19746"}],"version-history":[{"count":0,"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/posts\/19746\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/media\/13427"}],"wp:attachment":[{"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/media?parent=19746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/categories?post=19746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stepv.upv.es\/va\/wp-json\/wp\/v2\/tags?post=19746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}