{"id":3507,"date":"2017-11-07T08:35:37","date_gmt":"2017-11-07T07:35:37","guid":{"rendered":"http:\/\/www.stepv.upv.es\/?p=3507"},"modified":"2017-11-07T08:35:37","modified_gmt":"2017-11-07T07:35:37","slug":"novetats-carrera-professional","status":"publish","type":"post","link":"https:\/\/www.stepv.upv.es\/es\/novetats-carrera-professional\/","title":{"rendered":"Novedades carrera profesional"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 hundred-percent-fullwidth non-hundred-percent-height-scrolling\"  style='background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;'><div class=\"fusion-builder-row fusion-row \"><div  class=\"fusion-layout-column fusion_builder_column fusion_builder_column_1_1 fusion-builder-column-1 fusion-one-full fusion-column-first fusion-column-last fusion-column-no-min-height 1_1\"  style='margin-top:0px;margin-bottom:0px;'><div class=\"fusion-column-wrapper\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;\"   data-bg-url=\"\">El pasado 31 de octubre\u00a0<strong>la administraci\u00f3n acept\u00f3<\/strong>, en la mesa de negociaci\u00f3n del PAS,\u00a0<strong>las alegaciones de STEPV-I<\/strong>v para adaptar el encuadramiento en la carrera profesional a las novedades del decreto:\u00a0<strong>se reconocer\u00e1 el tiempo trabajado en aquellas categor\u00edas extinguidas como servicios prestados en la nueva categor\u00eda<\/strong>\u00a0en la que han quedado integradas.<\/p>\n<p>Aun as\u00ed, la administraci\u00f3n\u00a0<strong>no reconoce<\/strong>\u00a0el mismo derecho a las personas que ejercieron en las categor\u00edas extintas como interinos o con contrato laboral y obtuvieron la condici\u00f3n de funcionario de carrera en la nueva categor\u00eda, al hacer una interpretaci\u00f3n del art\u00edculo 11.3 (nueva redacci\u00f3n) del decreto de carrera profesional muy restrictiva y, en opini\u00f3n de STEPV-Iv muy equivocada. STEPV-Iv se plantea recurrir esta decisi\u00f3n.<\/p>\n<p><strong>Coordinadores de servicio<\/strong><\/p>\n<p>El complemento espec\u00edfico de las plazas de\u00a0<strong>Coordinadores de Servicio<\/strong>pasar\u00e1 a ser\u00a0<strong>E023<\/strong>. El acuerdo de 2015 que recoge este cambio podr\u00e1 ejecutarse gracias a haber negociado una nueva redacci\u00f3n de las funciones que se incluyeron en el \u00faltimo concurso.<\/p>\n<p><strong>Antig\u00fcedad en los baremos de concursos<\/strong><\/p>\n<p>En cuanto a los baremos, ha sido r<strong>echazada la propuesta de STEPV-Iv que pretend\u00eda ampliar el n\u00famero de a\u00f1os de antig\u00fcedad<\/strong>\u00a0que se computan en los concursos para dar valor al tiempo trabajado en la UPV. La propuesta pretend\u00eda romper con la din\u00e1mica en la que los cursos espec\u00edficos (controlados por el servicio de RR. HH) y las comisiones de servicio (la gran mayor\u00eda adjudicadas de forma arbitraria) tienen m\u00e1s peso que el tiempo trabajado. Se impuso la\u00a0<strong>propuesta de UGT, CC.OO. y UPV Sindical por la que los baremos no se modifican<\/strong>, como ya pas\u00f3 con los de promoci\u00f3n interna, con lo cual\u00a0<strong>el personal con m\u00e1s antig\u00fcedad en la Universidad pierde la oportunidad para que se les reconozcan los a\u00f1os trabajados<\/strong>.<\/p>\n<p>Por tanto, el baremo\u00a0<strong>contin\u00faa computando<\/strong>\u00a0\u00fanicamente\u00a0<strong>8 a\u00f1os<\/strong>\u00a0de antig\u00fcedad en cualquier administraci\u00f3n p\u00fablica (en cualquier grupo e incluyendo el tiempo de interinidad), y para STEPV-Iv\u00a0<strong>es como no computar ninguno<\/strong>, porque casi la totalidad de la plantilla de la UPV tiene m\u00e1s.<\/p>\n<p><strong>Oferta p\u00fablica de empleo 2017<\/strong><\/p>\n<p>Un punto del orden del d\u00eda ha sido establecer las bases para la pr\u00f3xima negociaci\u00f3n de la OPE, y parece que hay sinton\u00eda ente todos los agentes en evitar convocatorias con pocas plazas de las categor\u00edas m\u00e1s numerosas (Administrativos, Especialista T\u00e9cnico de Biblioteca, etc.)<\/p>\n<p><strong>Las negociaciones en punto muerto<\/strong><\/p>\n<p><strong>La Comisi\u00f3n<\/strong>\u00a0que debate los criterios para el\u00a0<strong>c\u00e1lculo de las necesidades del personal t\u00e9cnico de laboratorio<\/strong>\u00a0est\u00e1 encallada, lo que atrasa el calendario de negociaciones que se acord\u00f3 entre la administraci\u00f3n y los sindicatos. El Consejo de Gobierno encarg\u00f3 a un grupo de sabios la elaboraci\u00f3n de la propuesta de la administraci\u00f3n, pero no consiguen aportar conclusiones atribuyendo este hecho a que no han obtenido datos consistentes del personal t\u00e9cnico de laboratorio encuestado, sin ning\u00fan atisbo de autocr\u00edtica sobre si han formulado las preguntas adecuadas. El fracaso de este comit\u00e9 de sabios no permite avanzar con el calendario de negociaciones, y estamos a merced de la administraci\u00f3n y de aquello que les apetezca negociar.\u00a0<strong>STEPV-Iv instar\u00e1 al Consejo de Gobierno para que releve a los miembros de esta Comisi\u00f3n por su inoperancia<\/strong>.<\/p>\n<p>Seguiremos inform\u00e1ndoos.<\/p>\n<p>&nbsp;<div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":29775,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[843655,843668],"tags":[],"class_list":["post-3507","post","type-post","status-publish","format-standard","hentry","category-acces-i-promocio","category-drets-laborals"],"_links":{"self":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts\/3507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/users\/29775"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/comments?post=3507"}],"version-history":[{"count":0,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts\/3507\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/media?parent=3507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/categories?post=3507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/tags?post=3507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}