{"id":22569,"date":"2025-11-14T14:26:34","date_gmt":"2025-11-14T13:26:34","guid":{"rendered":"https:\/\/www.stepv.upv.es\/?p=22569"},"modified":"2025-11-17T08:50:48","modified_gmt":"2025-11-17T07:50:48","slug":"el-conveni-que-et-conve","status":"publish","type":"post","link":"https:\/\/www.stepv.upv.es\/es\/el-conveni-que-et-conve\/","title":{"rendered":"El convenio que te conviene"},"content":{"rendered":"<p>El d\u00eda 2 de diciembre empieza la negociaci\u00f3n del IV convenio colectivo del personal laboral de las universidades p\u00fablicas valencianas, y esto es importante para ti.<\/p>\n<p>\u00bfEs posible que el <strong>personal t\u00e9cnico y de gesti\u00f3n laboral y el personal investigador pre y posdoctoral<\/strong>\u00a0<strong>cobren salarios dignos iguales a los del PTGAS o PDI funcionario<\/strong>\u00a0que hacen tareas iguales?<\/p>\n<p><strong>En STEPV pensamos que s\u00ed.<\/strong><\/p>\n<p>\u00bfEs posible la\u00a0<strong>conciliaci\u00f3n\u00a0<\/strong>para el personal que trabaja con cargo en un proyecto?<\/p>\n<p><strong>En STEPV pensamos que s\u00ed.<\/strong><\/p>\n<p>\u00bfEl personal laboral temporal, \u00bfpuede tener v\u00edas de\u00a0<strong>estabilizaci\u00f3n y promoci\u00f3n<\/strong>?<\/p>\n<p><strong>En STEPV pensamos que s\u00ed.<\/strong><\/p>\n<p>\u00bfEs posible que el <strong>profesorado asociado y sustituto<\/strong>\u00a0<strong>cobre por las horas de preparaci\u00f3n, correcci\u00f3n y coordinaci\u00f3n\u00a0<\/strong>de las clases y no solo por las horas que pasa en el aula?<\/p>\n<p><strong>En STEPV pensamos que s\u00ed.<\/strong><\/p>\n<p>\u00bfEs posible que la totalidad de la docencia del profesorado asociado en cada jornada sea en\u00a0<strong>horas consecutivas<\/strong>?<\/p>\n<p><strong>En STEPV pensamos que s\u00ed.<\/strong><\/p>\n<p>\u00bfEs posible retribuirle al profesorado asociado y sustituto los\u00a0<strong>quinquenios, sexenios y las retribuciones adicionales<\/strong>\u00a0(que en otras universidades no cobran)?<\/p>\n<p><strong>En STEPV pensamos que s\u00ed.<\/strong><\/p>\n<p>\u00bfEs posible que el\u00a0<strong>profesorado permanente laboral cobre como el titular<\/strong>\u00a0de universidad, el\u00a0<strong>colaborador como el titular de escuela<\/strong>\u00a0y el\u00a0<strong>ayudante doctor el 90%<\/strong>\u00a0de lo que cobra un PPL?<\/p>\n<p><strong>En STEPV pensamos que s\u00ed.<\/strong><\/p>\n<p>\u00bfEs posible que se establezca un\u00a0<strong>m\u00e1ximo de 8 horas entre la primera clase y la \u00faltima<\/strong>\u00a0de cada jornada y otras medidas que permitan la conciliaci\u00f3n familiar del PDI?<\/p>\n<p><strong>En STEPV pensamos que s\u00ed.<\/strong><\/p>\n<p>\u00bfEs posible incluir un sistema de\u00a0<strong>protecci\u00f3n econ\u00f3mica<\/strong>\u00a0para el caso de que sea necesario el\u00a0<strong>reconocimiento de sexenios<\/strong>\u00a0por cambio de categor\u00eda laboral?<\/p>\n<p><strong>En STEPV pensamos que s\u00ed.<\/strong><\/p>\n<p>STEPV fue el \u00fanico sindicato que no firm\u00f3 el III convenio colectivo y ahora llegamos a la negociaci\u00f3n del IV convenio con\u00a0<b>fuerza e ideas<\/b>\u00a0para conseguir el convenio que te conviene.<\/p>\n<p>Si no sabes que regula un convenio colectivo y quieres saberlo\u00a0<a href=\"https:\/\/youtube.com\/shorts\/ruqB34HopPQ\" target=\"_blank\" rel=\"noopener\">aqu\u00ed ten\u00e9is este video.<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>El d\u00eda 2 de diciembre empieza la negociaci\u00f3n del IV convenio colectivo del personal laboral de las universidades p\u00fablicas valencianas, y esto es importante para ti. \u00bfEs posible que el personal t\u00e9cnico y de gesti\u00f3n laboral y el personal investigador pre y posdoctoral\u00a0cobren salarios dignos iguales a los del PTGAS o PDI funcionario\u00a0que hacen tareas [&hellip;]<\/p>\n","protected":false},"author":21175,"featured_media":22567,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[843674],"tags":[],"class_list":["post-22569","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acords-i-negociacions"],"_links":{"self":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts\/22569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/users\/21175"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/comments?post=22569"}],"version-history":[{"count":0,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts\/22569\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/media\/22567"}],"wp:attachment":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/media?parent=22569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/categories?post=22569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/tags?post=22569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}