{"id":21985,"date":"2025-05-20T11:56:38","date_gmt":"2025-05-20T09:56:38","guid":{"rendered":"https:\/\/www.stepv.upv.es\/?p=21985"},"modified":"2025-05-20T11:56:38","modified_gmt":"2025-05-20T09:56:38","slug":"vaga-general-29-de-maig","status":"publish","type":"post","link":"https:\/\/www.stepv.upv.es\/es\/vaga-general-29-de-maig\/","title":{"rendered":"HUELGA GENERAL 29 DE MAYO"},"content":{"rendered":"<p><\/p>\n<h2><b>Convoca STEPV &#8211; Intersindical Valenciana y otros sindicatos, con el apoyo de varios colectivos sociales.<\/b><\/h2>\n<p><b>El pueblo valenciano no olvida<\/b>. El 29 de octubre de 2024 la DANA provoc\u00f3 una tragedia que se pod\u00eda haber evitado. La respuesta del gobierno presidido por Maz\u00f3n fue tard\u00eda, negligente e irresponsable.<\/p>\n<p>En la UPV hay que recordar que la Inspecci\u00f3n de Trabajo detect\u00f3\u00a0<a href=\"https:\/\/www.stepv.upv.es\/va\/la-inspeccio-confirma-les-deficiencies-en-la-gestio-de-la-dana-denunciades-per-stepv\/\" target=\"_blank\" rel=\"noopener\">graves deficiencias<\/a>\u00a0<b>en la gesti\u00f3n de la emergencia en nuestra universidad<\/b>.<\/p>\n<p>Meses despu\u00e9s,\u00a0<b>el rectorado de la UPV<\/b>\u00a0blanqueaba el papel del presidente con un \u201c<a href=\"https:\/\/www.stepv.upv.es\/va\/vergonyaupv\/\" target=\"_blank\" rel=\"noopener\">selfi<\/a>\u201d a su lado, hiriendo la dignidad de nuestra instituci\u00f3n y de la comunidad universitaria.<\/p>\n<p>Muchas empresas obligaron a trabajar en condiciones meteorol\u00f3gicas peligrosas, ignorando avisos oficiales, con\u00a0<b>consecuencias graves para la salud y la vida de las trabajadoras.<\/b><\/p>\n<h2><b>El problema va m\u00e1s all\u00e1<\/b>.<\/h2>\n<p>El Consejo contin\u00faa recortando servicios p\u00fablicos \u2014sanidad, educaci\u00f3n, servicios sociales y emergencias\u2014 y beneficiando intereses privados, incluidas empresas condenadas por corrupci\u00f3n. Mientras el acceso a la vivienda acontece cada vez m\u00e1s dif\u00edcil. Familias afectadas por la DANA contin\u00faan abandonadas por la administraci\u00f3n.<\/p>\n<p><b>\u00a1El 29 de mayo, a la huelga general!<\/b><\/p>\n<p><b>Mi\u00e9rcoles 21 a las 12 h.<\/b><\/p>\n<p><b>Asamblea abierta en el sal\u00f3n de actos de la Facultad de Ciencias Sociales en la avenida de los Naranjos.<\/b><\/p>\n<p>\u00a1Ven y participa! \u00a1Las universidades se organizan y se movilizan!<\/p>","protected":false},"excerpt":{"rendered":"<p>Convoca STEPV &#8211; Intersindical Valenciana y otros sindicatos, con el apoyo de varios colectivos sociales. El pueblo valenciano no olvida. El 29 de octubre de 2024 la DANA provoc\u00f3 una tragedia que se pod\u00eda haber evitado. La respuesta del gobierno presidido por Maz\u00f3n fue tard\u00eda, negligente e irresponsable. En la UPV hay que recordar que [&hellip;]<\/p>\n","protected":false},"author":21175,"featured_media":21983,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[843658],"tags":[],"class_list":["post-21985","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actes-i-mobilitzacions"],"_links":{"self":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts\/21985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/users\/21175"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/comments?post=21985"}],"version-history":[{"count":0,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts\/21985\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/media\/21983"}],"wp:attachment":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/media?parent=21985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/categories?post=21985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/tags?post=21985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}