{"id":21296,"date":"2024-03-07T12:11:21","date_gmt":"2024-03-07T11:11:21","guid":{"rendered":"https:\/\/www.stepv.upv.es\/?p=21296"},"modified":"2024-03-13T11:16:59","modified_gmt":"2024-03-13T10:16:59","slug":"reduccio-de-jornada-festes-locals","status":"publish","type":"post","link":"https:\/\/www.stepv.upv.es\/es\/reduccio-de-jornada-festes-locals\/","title":{"rendered":"Reducci\u00f3n de jornada fiestas locales"},"content":{"rendered":"<p>En el siguiente\u00a0<a href=\"https:\/\/www.stepv.upv.es\/wp-content\/uploads\/2024\/03\/FESTES-LOCALS_FALLES_v2.pdf\" target=\"_blank\" rel=\"noopener\">enlace<\/a>, encontrar\u00e9is un\u00a0<b>resumen<\/b>\u00a0de las diferentes opciones que podemos encontrar a la hora de aplicar la\u00a0<b>reducci\u00f3n de 6 horas y 30 minutos durante la semana de Fallas<\/b>. Esta reducci\u00f3n se aplica en las fiestas locales del campus de Valencia y Gand\u00eda.<\/p>\n<p>Adem\u00e1s, en referencia al per\u00edodo de\u00a0<b>Semana Santa y Pascua<\/b>, os recordamos que, tal como se indica en el calendario laboral aprobado:<\/p>\n<p><i>\u00abDe conformidad con lo establecido en el\u00a0<b>Apartado 5.5 del Acuerdo de Conciliaci\u00f3n<\/b>, el personal tendr\u00e1 derecho a\u00a0<b>disfrutar<\/b>\u00a0de un m\u00e1ximo de las horas\u00a0<b>equivalentes a 4 d\u00edas de trabajo<\/b>, comprendidos dentro del per\u00edodo\u00a0<b>entre el martes 2 y el viernes 5 de abril, ambos inclusive.<\/b><\/i><\/p>\n<p><i>El personal que tenga asignada jornada laboral en festivos o de fines de semana, el per\u00edodo comprender\u00e1 desde el martes d\u00eda 2 al lunes 8 de abril de 2024&#8243;<\/i><\/p>","protected":false},"excerpt":{"rendered":"<p>En el siguiente\u00a0enlace, encontrar\u00e9is un\u00a0resumen\u00a0de las diferentes opciones que podemos encontrar a la hora de aplicar la\u00a0reducci\u00f3n de 6 horas y 30 minutos durante la semana de Fallas. Esta reducci\u00f3n se aplica en las fiestas locales del campus de Valencia y Gand\u00eda. Adem\u00e1s, en referencia al per\u00edodo de\u00a0Semana Santa y Pascua, os recordamos que, tal [&hellip;]<\/p>\n","protected":false},"author":21175,"featured_media":21291,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[843680],"tags":[],"class_list":["post-21296","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altres-noticies-dinteres"],"_links":{"self":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts\/21296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/users\/21175"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/comments?post=21296"}],"version-history":[{"count":0,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts\/21296\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/media\/21291"}],"wp:attachment":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/media?parent=21296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/categories?post=21296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/tags?post=21296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}