{"id":20670,"date":"2023-07-10T10:03:12","date_gmt":"2023-07-10T08:03:12","guid":{"rendered":"https:\/\/www.stepv.upv.es\/?p=20670"},"modified":"2024-03-04T12:11:20","modified_gmt":"2024-03-04T11:11:20","slug":"la-conversio-dels-cod-en-ppl","status":"publish","type":"post","link":"https:\/\/www.stepv.upv.es\/es\/la-conversio-dels-cod-en-ppl\/","title":{"rendered":"La conversi\u00f3n de los COD EN PPL"},"content":{"rendered":"<p>En la \u00faltima mesa negociadora, los sindicatos pedimos al VPOA que empezara la transformaci\u00f3n del\u00a0<b>Profesorado Contratado Doctor en Profesorado Permanente<\/b>\u00a0<b>Laboral<\/b>\u00a0para adaptarnos a la nueva\u00a0<b>LOSU<\/b>. Por parte de STEPV se puso de ejemplo el proceso que hab\u00eda comenzado la UV, donde s\u00f3lo es necesaria una solicitud de la persona interesada.<\/p>\n<p>Aunque nos dijo que nos contestar\u00eda y no lo ha hecho, el VPOA ya ha puesto en marcha la transformaci\u00f3n, que al igual que en la UV, s\u00f3lo ser\u00e1 necesaria una solicitud, como indica la LOSU.<\/p>\n<p>Recomendamos a todo el Profesorado Contratado Doctor que se integre como Profesorado Permanente Laboral, porque, de facto, s\u00f3lo supone un cambio de nombre, sin que se vean afectados ninguno de sus derechos o deberes, y siempre es mejor no pertenecer a un cuerpo (el COD) declarado a extinguir por la LOSU.<\/p>\n<p>Si tienes cualquier duda o consulta, puedes contactar con STEPV en el correo stepv@upv.es y en las extensiones 77046 o 79149.<\/p>","protected":false},"excerpt":{"rendered":"<p>En la \u00faltima mesa negociadora, los sindicatos pedimos al VPOA que empezara la transformaci\u00f3n del\u00a0Profesorado Contratado Doctor en Profesorado Permanente\u00a0Laboral\u00a0para adaptarnos a la nueva\u00a0LOSU. Por parte de STEPV se puso de ejemplo el proceso que hab\u00eda comenzado la UV, donde s\u00f3lo es necesaria una solicitud de la persona interesada. Aunque nos dijo que nos contestar\u00eda [&hellip;]<\/p>\n","protected":false},"author":21175,"featured_media":325,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[843655],"tags":[],"class_list":["post-20670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acces-i-promocio"],"_links":{"self":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts\/20670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/users\/21175"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/comments?post=20670"}],"version-history":[{"count":0,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts\/20670\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/media\/325"}],"wp:attachment":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/media?parent=20670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/categories?post=20670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/tags?post=20670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}