{"id":20644,"date":"2023-06-16T14:11:20","date_gmt":"2023-06-16T12:11:20","guid":{"rendered":"https:\/\/www.stepv.upv.es\/?p=20644"},"modified":"2024-03-04T11:42:58","modified_gmt":"2024-03-04T10:42:58","slug":"altra-decisio-absurda-amb-el-teletreball","status":"publish","type":"post","link":"https:\/\/www.stepv.upv.es\/es\/altra-decisio-absurda-amb-el-teletreball\/","title":{"rendered":"Otra decisi\u00f3n absurda con el teletrabajo"},"content":{"rendered":"<p>La administraci\u00f3n\u00a0<b>de forma unilateral<\/b>\u00a0ha decidido suspender el teletrabajo para el personal adscritos a Centros durante los meses de julio y septiembre.<\/p>\n<p>Esta decisi\u00f3n\u00a0<b>no ha sido ni negociada ni explicada<\/b>\u00a0a las organizaciones sindicales, y supone un incumplimiento del acuerdo aprobado por el Consejo de Gobierno, donde especifica, en la disposici\u00f3n, que del 1 de septiembre al 15 de octubre\u00a0<b>de\u00a0<u>2022<\/u><\/b>\u00a0quedaba suspendido el teletrabajo en los centros (escuelas y facultades) y departamentos.<\/p>\n<p>Para la administraci\u00f3n viene siendo demasiado\u00a0<b>habitual incumplir los acuerdos que ha firmado<\/b>\u00a0porque a algunas personas no los gustan. Esta situaci\u00f3n crea\u00a0<b>inseguridad jur\u00eddica.<\/b><\/p>\n<p>Desde STEPV, exigimos la rectificaci\u00f3n, y si procede implementar una medida como esta que pensamos no est\u00e1 fundada porque\u00a0<b>el teletrabajo tambi\u00e9n es trabajo<\/b>, la negociaci\u00f3n previa con la representaci\u00f3n de los trabajadores y trabajadoras.<\/p>\n<p><a href=\"https:\/\/www.stepv.upv.es\/wp-content\/uploads\/2023\/06\/Teletreball_juny_2023_SOLGEN_184516.pdf.pdf\" target=\"dKEGdKW_-bSF7w8GUIbc8YK\" rel=\"noopener noreferrer\">Puedes consultar el escrito presentado a la Vicegerencia de Recursos Humanos aqu\u00ed.<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>La administraci\u00f3n\u00a0de forma unilateral\u00a0ha decidido suspender el teletrabajo para el personal adscritos a Centros durante los meses de julio y septiembre. Esta decisi\u00f3n\u00a0no ha sido ni negociada ni explicada\u00a0a las organizaciones sindicales, y supone un incumplimiento del acuerdo aprobado por el Consejo de Gobierno, donde especifica, en la disposici\u00f3n, que del 1 de septiembre al [&hellip;]<\/p>\n","protected":false},"author":14845,"featured_media":20297,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[843674],"tags":[],"class_list":["post-20644","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acords-i-negociacions"],"_links":{"self":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts\/20644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/users\/14845"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/comments?post=20644"}],"version-history":[{"count":0,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts\/20644\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/media\/20297"}],"wp:attachment":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/media?parent=20644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/categories?post=20644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/tags?post=20644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}