{"id":20565,"date":"2023-04-06T07:35:34","date_gmt":"2023-04-06T05:35:34","guid":{"rendered":"https:\/\/www.stepv.upv.es\/?p=20565"},"modified":"2024-03-05T14:20:40","modified_gmt":"2024-03-05T13:20:40","slug":"la-fundacio-servipoli-polemica-i-precaria","status":"publish","type":"post","link":"https:\/\/www.stepv.upv.es\/es\/la-fundacio-servipoli-polemica-i-precaria\/","title":{"rendered":"La Fundaci\u00f3n SERVIPOLI, pol\u00e9mica y precaria"},"content":{"rendered":"<p>Hace unos d\u00edas, la Fundaci\u00f3n SERVIPOLI anunci\u00f3 la suspensi\u00f3n de actividad de sus trabajadores y trabajadoras desde el d\u00eda 7 hasta el 17 de este mes, una medida que sorprendi\u00f3 a los estudiantes de la UPV y que se anunci\u00f3 sin preaviso alguno. Esta medida significa una p\u00e9rdida de un tercio de la escasa remuneraci\u00f3n que cobran ya este mes.\u00a0<strong>Es decir, han sido despedidos temporalmente por no tener que pagarles las vacaciones<\/strong>.<\/p>\n<p>Adem\u00e1s, de los 10 d\u00edas que se dejan a los trabajadores en la calle, s\u00f3lo cuatro son d\u00edas laborales, el resto son fines de semana y festivos, una medida grav\u00edsima y sin precedentes.<\/p>\n<p>Desde STEPV, hemos manifestado reiteradamente nuestras preocupaciones sobre las pr\u00e1cticas de SERVIPOLI. Por un lado,\u00a0<strong>consideramos que se trata de empleo p\u00fablico<\/strong>, aunque sea temporal,\u00a0<strong>en cuya selecci\u00f3n no se garantiza el principio constitucional de igualdad<\/strong>\u00a0en el acceso a la funci\u00f3n p\u00fablica, lo que no impide que nuestro sindicato defienda los derechos laborales de estas personas.<\/p>\n<p>Por otra parte, hemos denunciado\u00a0<strong>que contratar a estudiantes para realizar tareas<\/strong>\u00a0de dise\u00f1o, fotograf\u00eda o administrativas\u00a0<strong>por poco m\u00e1s de 400\u20ac al mes es una pr\u00e1ctica censurable<\/strong>, ya que utiliza\u00a0<strong>mano de obra barata<\/strong>\u00a0en lugar de contratar a trabajadores y trabajadoras con derechos laborales plenos para realizar estas tareas.<\/p>\n<p>Desde STEPV instamos a todo el patronato de la Fundaci\u00f3n SERVIPOLI, y\u00a0<strong>especialmente a CCOO y UGT<\/strong>, como sindicatos de clase,\u00a0<strong>a tomar las medidas necesarias para rectificar<\/strong>\u00a0esta situaci\u00f3n urgentemente.<\/p>\n<p><strong>Muchos \u00abservipolis\u00bb dependen de estos ingresos<\/strong>\u00a0para poder pagar el alquiler y comida, considerando que muchos de ellos no reciben soporte familiar de ning\u00fan tipo. Por eso es necesario preguntarse por qu\u00e9 las personas responsables de SERVIPOLI no son sensibles a estas necesidades, y por qu\u00e9 interpretan las leyes laborales en contra de los trabajadores que deben cuidar.<\/p>","protected":false},"excerpt":{"rendered":"<p>Hace unos d\u00edas, la Fundaci\u00f3n SERVIPOLI anunci\u00f3 la suspensi\u00f3n de actividad de sus trabajadores y trabajadoras desde el d\u00eda 7 hasta el 17 de este mes, una medida que sorprendi\u00f3 a los estudiantes de la UPV y que se anunci\u00f3 sin preaviso alguno. Esta medida significa una p\u00e9rdida de un tercio de la escasa remuneraci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":14845,"featured_media":20427,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[843668],"tags":[],"class_list":["post-20565","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-drets-laborals"],"_links":{"self":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts\/20565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/users\/14845"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/comments?post=20565"}],"version-history":[{"count":0,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts\/20565\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/media\/20427"}],"wp:attachment":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/media?parent=20565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/categories?post=20565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/tags?post=20565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}