{"id":19769,"date":"2022-02-14T09:24:38","date_gmt":"2022-02-14T08:24:38","guid":{"rendered":"https:\/\/www.stepv.upv.es\/?p=19769"},"modified":"2022-02-14T09:24:38","modified_gmt":"2022-02-14T08:24:38","slug":"resum-del-consell-de-govern-3-2-2022","status":"publish","type":"post","link":"https:\/\/www.stepv.upv.es\/es\/resum-del-consell-de-govern-3-2-2022\/","title":{"rendered":"Resumen del Consejo de Gobierno 3\/2\/2022"},"content":{"rendered":"<p>La sesi\u00f3n de febrero del Consejo de Gobierno no tuvo acuerdos destacables, pero en el informe del Rector y en los Ruegos y preguntas surgieron temas que seguro te preocupan, seas PDI, PAS o Personal Laboral.<\/p>\n<p>Continuamos con el formato de v\u00eddeo-blog porque tuvo una gran acogida en general, confiamos en que os sea m\u00e1s ameno.<\/p>\n<div class=\"fusion-video fusion-youtube fusion-aligncenter\" style=\"max-width:600px;max-height:360px; width:100%\" data-autoplay=\"1\"><div class=\"video-shortcode\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/8T2UWz2KYRQ?wmode=transparent&autoplay=0\" width=\"600\" height=\"360\" allowfullscreen allow=\"autoplay; fullscreen\"><\/iframe><\/div><\/div>\n<p>&nbsp;<\/p>\n<p>En el v\u00eddeo de hoy hablaremos de:<\/p>\n<p>0:38 C\u00f3mo nos afecta la reforma laboral<\/p>\n<p>2:41 \u00bfNovedades? en les retribuciones adicionales de 2019 y 2020<\/p>\n<p>3:59 Procesos de estabilizaci\u00f3n<\/p>\n<p>5:22 NOA<\/p>\n<p>6:43 Reflexiones sobre la calidad democr\u00e1tica de nuestra UPV<\/p>\n<p>8:24 Mi elecci\u00f3n como representante del Consejo de Gobierno en el Consejo Social<\/p>\n<p>9:03 Noticias breves del Informe del Rector<\/p>\n<p>9:34 Relaci\u00f3n de acuerdos<\/p>\n<p><strong><em>Vuestros ojos y vuestra voz<\/em><\/strong>.<\/p>","protected":false},"excerpt":{"rendered":"<p>La sesi\u00f3n de febrero del Consejo de Gobierno no tuvo acuerdos destacables, pero en el informe del Rector y en los Ruegos y preguntas surgieron temas que seguro te preocupan, seas PDI, PAS o Personal Laboral. Continuamos con el formato de v\u00eddeo-blog porque tuvo una gran acogida en general, confiamos en que os sea m\u00e1s [&hellip;]<\/p>\n","protected":false},"author":11580,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1099362,843678],"tags":[],"class_list":["post-19769","post","type-post","status-publish","format-standard","hentry","category-consell-de-govern","category-organs-de-govern"],"_links":{"self":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts\/19769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/users\/11580"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/comments?post=19769"}],"version-history":[{"count":0,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts\/19769\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/media?parent=19769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/categories?post=19769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/tags?post=19769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}