{"id":13256,"date":"2018-10-22T09:46:05","date_gmt":"2018-10-22T07:46:05","guid":{"rendered":"https:\/\/www.stepv.upv.es\/?p=13256"},"modified":"2018-10-22T09:46:05","modified_gmt":"2018-10-22T07:46:05","slug":"de-llocs-eventuals-i-direccions-darea","status":"publish","type":"post","link":"https:\/\/www.stepv.upv.es\/es\/de-llocs-eventuals-i-direccions-darea\/","title":{"rendered":"De puestos eventuales y direcciones de \u00e1rea"},"content":{"rendered":"<p>Dicen que una ardilla puede cruzar el Campus de Vera, de este a oeste, saltando de direcci\u00f3n de \u00e1rea en direcci\u00f3n de \u00e1rea y de personal eventual a personal eventual sin tocar suelo<\/p>\n<p>Resulta sorprendente que\u00a0<strong>la UPV tenga m\u00e1s personal eventual que el resto de universidades p\u00fablicas valencianas juntas.<\/strong>\u00a0Este personal se nombra a dedo y recibe las retribuciones que fija el Rector para realizar funciones expresamente calificadas como de\u00a0<strong>confianza o asesoramiento especial<\/strong>. \u00a1La UPV cuenta con 21 puestos de trabajo de esta naturaleza! \u00bfSon tantas las cuestiones de confianza que necesitan de asesoramiento?<\/p>\n<p>Por otra parte, cuando llega el oto\u00f1o las Direcciones de \u00c1rea se multiplican como setas. En dos a\u00f1os estas direcciones\u00a0<strong>han aumentado de 20 a 29<\/strong>. STEPV-Iv opina que en algunos casos no responden a las necesidades reales del servicio, ya que\u00a0<strong>duplican las funciones del puesto de Jefe de Servicio<\/strong> y se hace m\u00e1s evidente cuando una misma persona desempe\u00f1a los dos cargos.<\/p>\n<p>La Direcci\u00f3n de \u00c1rea comporta un\u00a0<strong>complemento retributivo equivalente a la Direcci\u00f3n de un Departamento<\/strong>, adem\u00e1s de la\u00a0<strong>reducci\u00f3n de carga docente<\/strong> de 12 cr\u00e9ditos\u00a0en el caso del PDI<\/p>\n<p>STEPV-Iv ha\u00a0<a href=\"http:\/\/www.stepv.upv.es\/wp-content\/uploads\/2018\/10\/direccions-area.pdf\">solicitado<\/a>, en cumplimiento de la ley\u00a0 de transparencia, la\u00a0<strong>publicaci\u00f3n de las funciones<\/strong> de todos los puestos de trabajo eventual y de los cargos de Direcci\u00f3n de \u00c1rea. Adem\u00e1s, invitamos al Rectorado a sumarse a la iniciativa de la Generalitat y publicar los curr\u00edculums de las personas que ocupan cargos de asesor\u00eda y confianza.<\/p>\n<p>Es un buen momento para que el Rector demuestre que realmente somos la Administraci\u00f3n transparente, a la que siempre hace alusi\u00f3n.<\/p>","protected":false},"excerpt":{"rendered":"<p>Dicen que una ardilla puede cruzar el Campus de Vera, de este a oeste, saltando de direcci\u00f3n de \u00e1rea en direcci\u00f3n de \u00e1rea y de personal eventual a personal eventual sin tocar suelo Resulta sorprendente que\u00a0la UPV tenga m\u00e1s personal eventual que el resto de universidades p\u00fablicas valencianas juntas.\u00a0Este personal se nombra a dedo y [&hellip;]<\/p>\n","protected":false},"author":11580,"featured_media":1108,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[843680,843682],"tags":[],"class_list":["post-13256","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altres-noticies-dinteres","category-mes-transparencia-mes-garanties"],"_links":{"self":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts\/13256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/users\/11580"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/comments?post=13256"}],"version-history":[{"count":0,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts\/13256\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/media\/1108"}],"wp:attachment":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/media?parent=13256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/categories?post=13256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/tags?post=13256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}