{"id":12946,"date":"2019-05-30T22:00:21","date_gmt":"2019-05-30T20:00:21","guid":{"rendered":"https:\/\/www.stepv.upv.es\/?p=12946"},"modified":"2019-05-30T22:00:21","modified_gmt":"2019-05-30T20:00:21","slug":"consell-de-govern-18-de-juliol","status":"publish","type":"post","link":"https:\/\/www.stepv.upv.es\/es\/consell-de-govern-18-de-juliol\/","title":{"rendered":"Resumen del Consejo de Gobierno del dia 30 de mayo"},"content":{"rendered":"<p>El Consejo de Gobierno ha aprobado lo siguiente:<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <strong>Modificaci\u00f3n del reglamento del Consejo de Gobierno<\/strong> para que la comunicaci\u00f3n del orden del d\u00eda sea a trav\u00e9s de medios electr\u00f3nicos y se evite el env\u00edo en papel. Nos alegramos de esta medida ecol\u00f3gica que, adem\u00e1s, comporta un ahorro de trabajo y de dinero.<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <strong>Modificaci\u00f3n de asignaci\u00f3n de la docencia a los departamentos<\/strong>. El cambio permitir\u00e1 que no se pueda asignar docencia a una profesora o un profesor con una sanci\u00f3n administrativa firme, incluso si por distintos motivos no se puede ejecutar.<\/p>\n<p>Hemos votado en contra al considerar qu\u00e9 si la ley no permite aplicar una sanci\u00f3n administrativa durante una baja m\u00e9dica, por ejemplo, la Universidad tiene que respetar esta garant\u00eda que la ley ofrece y no ejecutarla de una forma encubierta.<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Creaci\u00f3n de 5 plazas de CU, 5 plazas de T\u00da y 5 de COD dentro del <strong>Programa de atracci\u00f3n de talento,<\/strong> para el curso 2019-2020. El vicerrector nos ha explicado que se puede pensar que no puede haber personas con un curr\u00edculum destacable para las plazas de COD, aun as\u00ed, estas plazas se han creado porque hay personas con un curr\u00edculum investigador muy importante pero no tanto en cuanto a la docencia, y como consecuencia solo pueden conseguir acreditaci\u00f3n a COD.<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <strong>Oferta P\u00fablica de Empleo PDI 2019<\/strong>, aprobada previamente por la mesa de negociaci\u00f3n por unanimidad. Se crean las plazas siguientes:<\/p>\n<p>Plazas de categor\u00eda superior en aquellos departamentos donde hay personal no Asociado que se ha acreditado: 25 COD, 10 T\u00da, 19 de CU.<\/p>\n<p>5 plazas de T\u00da en los departamentos donde el profesorado Asociado se ha acreditado en esta figura.<\/p>\n<p>Plazas de profesorado a tiempo completo en otros departamentos donde se vincula a la reducci\u00f3n de dos plazas de profesorado Asociado, por lo que el n\u00famero de personas de este colectivo que este a\u00f1o no renovar\u00e1 el contrato es significativo. Por otro lado, es cierto que la transformaci\u00f3n de trabajo en precario, que consideremos que es el contrato de profesorado asociado, en trabajo estable es un avance, y a la vez se da oportunidades a este colectivo de conseguir plaza a tiempo completo. La mesa negociadora est\u00e1 tratando de acordar unos criterios homog\u00e9neos para la no renovaci\u00f3n de contrato de personal Asociado.<\/p>\n<p>22 COD, y 17 COD con el requisito I3 (15% m\u00ednimo seg\u00fan la ley de Presupuestos).<\/p>\n<p>Finalmente, la propuesta de OPO 2019 la conforman un total de 113 plazas, incluidas las 15 de atracci\u00f3n de talento.<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 M<strong>odificaciones de la RLT de PAS<\/strong>, aprobadas por unanimidad en la mesa de negociaci\u00f3n. Olaya ha destacado que la administraci\u00f3n ha sido muy lenta al negociar y modificar en la RLT el cambio de situaciones de algunos puestos de trabajo. Ha ocurrido que se ha tardado 3 a\u00f1os y medio para incluir la exclusividad en algunas plazas. De ahora en adelante, la administraci\u00f3n llevar\u00e1 cada mes los cambios de las plazas a la mesa negociadora.<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 A propuesta de Olaya, los asuntos acordados en las mesas de negociaci\u00f3n se trasladar\u00e1n al Consejo de Gobierno acompa\u00f1ados de un certificado de la Secretar\u00eda del \u00f3rgano para evitar dudas.<\/p>\n<p>Otros asuntos que cabe destacar son:<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Se ha informado que el presidente nuevo de la CRUE es el rector de la Universidad de C\u00f3rdoba. El rector de la UPV, Francisco Mora, ocupar\u00e1 el cargo de Vicepresidente.<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 En cumplimiento del compromiso que tiene la Universidad con el medio ambiente, y a petici\u00f3n de un miembro en la anterior sesi\u00f3n del Consejo de Gobierno, por primera vez se ha sustituido el agua embotellada por jarras y vasos de vidrio en este Consejo, para reducir el pl\u00e1stico. En la sesi\u00f3n de Consejo Social del d\u00eda 12 de junio, Olaya ha pedido que se empleara esta misma medida.<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Ante el rumor, a estas alturas confirmado, que el nuevo Consell del Bot\u00e0nic contar\u00e1 con una Conselleria de Universidades, diferenciada de la de Educaci\u00f3n, Olaya ha preguntado al rector por su valoraci\u00f3n. El rector considera muy positivo la existencia de esta Conselleria para que exista una sensibilidad especial hacia las universidades. Olaya tambi\u00e9n lo cree sabiendo que la nueva Consellera es una profesora de la Universitat d&#8217;Alacant.<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 C\u00f3mo puedes ver en esta noticia<\/p>\n<p><a href=\"https:\/\/www.upv.es\/noticias-upv\/noticia-10607-up-steam-es.html\">https:\/\/www.upv.es\/noticias-upv\/noticia-10607-up-steam-es.html<\/a>, el d\u00eda 5 de junio Olaya form\u00f3 parte de la representaci\u00f3n del Consejo Social para valorar y seleccionar los equipos finalistas del concurso UP STEAM. Este proyecto est\u00e1 enfocado al alumnado de secundaria de institutos de Valencia. Cuenta con la colaboraci\u00f3n de la Real Academia de Ingenier\u00eda y persigue acercar la ciencia, la tecnolog\u00eda, la ingenier\u00eda, el arte y las matem\u00e1ticas al alumnado de forma divertida y creativa (\u00e1mbito conocido como STEAM, por el acr\u00f3nimo en ingl\u00e9s), adem\u00e1s de incentivar las vocaciones en estas carreras sobre todo a las ni\u00f1as.<\/p>\n<p>Para Olaya, valorar 51 videos de estudiantes de secundaria fue una tarea dif\u00edcil pero gratificante, y destaca el gran trabajo de los participantes y en especial de los 6 equipos finalistas.<\/p>\n<p>Hace pocos d\u00edas todos los miembros de la comunidad universitaria recibieron una invitaci\u00f3n para asistir a la final de este concurso que se celebr\u00f3 el jueves 27 de junio a las 18.00 horas en el Auditorio Mar Rojo del Oceanogr\u00e0fic.<\/p>\n<p>Como siempre, te animo a enviarnos propuestas y consultas para trasladarlas al Consejo de Gobierno y al Consejo Social. Tambi\u00e9n apreciamos las cr\u00edticas para poder mejorar en nuestra tarea.<\/p>\n<p><a href=\"mailto:omarpi@upv.es\">omarpi@upv.es<\/a> \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Olaya Mart\u00ednez Piera (representante del PAS en el Consejo de Gobierno y Consejo Social)<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"mailto:mdiamon@hma.upv.es\">mdiamon@hma.upv.es<\/a> \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Silvia D\u00edaz-Alejo Monterde (representando otro PDI)<\/p>\n<p><a href=\"mailto:smoreno@upvnet.upv.es\">smoreno@upvnet.upv.es<\/a> \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Salom\u00e9 Moreno Navarro (representando otro PDI)<\/p>","protected":false},"excerpt":{"rendered":"<p>El Consejo de Gobierno ha aprobado lo siguiente: &#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Modificaci\u00f3n del reglamento del Consejo de Gobierno para que la comunicaci\u00f3n del orden del d\u00eda sea a trav\u00e9s de medios electr\u00f3nicos y se evite el env\u00edo en papel. Nos alegramos de esta medida ecol\u00f3gica que, adem\u00e1s, comporta un ahorro de trabajo y de dinero. &#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Modificaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":29775,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1099362],"tags":[],"class_list":["post-12946","post","type-post","status-publish","format-standard","hentry","category-consell-de-govern"],"_links":{"self":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts\/12946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/users\/29775"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/comments?post=12946"}],"version-history":[{"count":0,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts\/12946\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/media?parent=12946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/categories?post=12946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/tags?post=12946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}