{"id":1264,"date":"2016-11-18T11:27:28","date_gmt":"2016-11-18T10:27:28","guid":{"rendered":"http:\/\/vijufer.webs.upv.es\/?p=1264"},"modified":"2016-11-18T11:27:28","modified_gmt":"2016-11-18T10:27:28","slug":"la-mesa-general-acorda-una-ampliacio-de-les-prestacions-per-incapacitat-temporal-i-del-permis-de-paternitat","status":"publish","type":"post","link":"https:\/\/www.stepv.upv.es\/es\/la-mesa-general-acorda-una-ampliacio-de-les-prestacions-per-incapacitat-temporal-i-del-permis-de-paternitat\/","title":{"rendered":"La mesa general acuerda una ampliaci\u00f3n de las prestaciones por Incapacidad Temporal y del permiso de paternidad"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 hundred-percent-fullwidth non-hundred-percent-height-scrolling\"  style='background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;'><div class=\"fusion-builder-row fusion-row \"><div  class=\"fusion-layout-column fusion_builder_column fusion_builder_column_1_1 fusion-builder-column-0 fusion-one-full fusion-column-first fusion-column-last fusion-column-no-min-height 1_1\"  style='margin-top:0px;margin-bottom:0px;'><div class=\"fusion-column-wrapper\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;\"   data-bg-url=\"\">El pasado jueves d\u00eda 17 de noviembre se reuni\u00f3 la mesa general de negociaci\u00f3n para tratar, entre otro<\/p>\n<ol>\n<li>\n<h3><em> Ampliaci\u00f3n de las prestaciones IT (Incapacidad Temporal)<\/em><\/h3>\n<\/li>\n<\/ol>\n<p>Se presentaron, por parte de los sindicatos, distintas propuestas encaminadas a la aprobaci\u00f3n de nuevos supuestos de baja que no comporten ninguna retenci\u00f3n, es decir recibir el 100% del sueldo.<\/p>\n<p><strong><a href=\"http:\/\/vijufer.webs.upv.es\/wp-content\/uploads\/2016\/12\/RETRIBUCIONES-POR-IT.docx\"> Anexamos el documento del acuerdo con todos los supuestos<\/a>.<\/strong><\/p>\n<p>En esta \u00faltima Mesa se a\u00f1adieron los siguientes<\/p>\n<p>&#8211; Traumatismos y lesiones o secuelas que ocasionen incapacidad para el desarrollo de nuestra actividad cotidiana y el preceptivo periodo de observaci\u00f3n posterior a un traumatismo craneoencef\u00e1lico que conlleve incapacidad transitorio<\/p>\n<p>&#8211; C\u00f3lico nefr\u00edtico<\/p>\n<p>Adem\u00e1s, se ha reclamado por parte de todos los sindicatos la retirada de las limitaciones para el cobro del 100% de todas las bajas, ya que en otras administraciones se ha llegado a acuerdos amplios que englobar\u00edan todos los supuestos. \u00a0En consecuencia, se acord\u00f3 solicitar un informe jur\u00eddico al respecto. Si dicho informe concluye que no se vulnera la ley, la UPV autom\u00e1ticamente retirar\u00e1 dichas restricciones.<\/p>\n<p>Igualmente se acord\u00f3 que a solicitud del interesado se realizar\u00e1 el pago con car\u00e1cter retroactivo desde 2012 de todas las bajas que se hayan producido durante estos periodos.<\/p>\n<ol start=\"2\">\n<li>\n<h3><em> Proceso electoral de los Delegados de Prevenci\u00f3n en Gandia y Alcoi<\/em><\/h3>\n<\/li>\n<\/ol>\n<p>Aunque este acuerdo se tom\u00f3 ya en el mes de Julio en la Mesa General de Negociaci\u00f3n, todav\u00eda no se ha iniciado el proceso electoral. Stepv-Iv ha solicitado en distintas ocasiones la puesta en marcha de dicho proceso y a pesar de las buenas palabras y promesas por parte de la administraci\u00f3n de celebrar cuanto antes las elecciones, a d\u00eda de hoy siguen sin celebrarse. En cualquier caso, el acuerdo que adopto la mesa fue celebrar las elecciones durante el mes de diciembre.<\/p>\n<ol start=\"3\">\n<li>\n<h3>Ampliaci\u00f3n del permiso de paternidad a 6 semanas y reducci\u00f3n de jornada\u00a0 para las empleadas v\u00edctimas de violencia de g\u00e9nero<\/h3>\n<\/li>\n<\/ol>\n<p>Se han modificado los siguientes permisos del Plan Concilia de la Universitat:<\/p>\n<p>&#8211;\u00a0 \u00a0El permiso de paternidad de 20 d\u00edas a 6 semanas.<\/p>\n<p>&#8211;\u00a0 \u00a0El de violencia de g\u00e9nero pasa a tener una reducci\u00f3n de un tercio o el 50% de la jornada. En el primer caso sin merma de retribuciones y en el segundo con una disminuci\u00f3n, aproximadamente, del 17%.<div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":11580,"featured_media":47,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[843674,843668,843672],"tags":[],"class_list":["post-1264","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acords-i-negociacions","category-drets-laborals","category-prevencio-i-salut-laboral"],"_links":{"self":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts\/1264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/users\/11580"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/comments?post=1264"}],"version-history":[{"count":0,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/posts\/1264\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/media\/47"}],"wp:attachment":[{"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/media?parent=1264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/categories?post=1264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stepv.upv.es\/es\/wp-json\/wp\/v2\/tags?post=1264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}